{"id":641,"date":"2017-02-14T16:34:28","date_gmt":"2017-02-14T16:34:28","guid":{"rendered":"http:\/\/elviox.gr\/portfolio-item\/ksilino-spiti\/"},"modified":"2017-03-10T21:36:54","modified_gmt":"2017-03-10T21:36:54","slug":"ksilino-spiti","status":"publish","type":"portfolio","link":"https:\/\/elviox.gr\/en\/portfolio-item\/ksilino-spiti\/","title":{"rendered":"Wooden house"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":335,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"portfolio-types":[31],"class_list":["post-641","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio-types--elviox-en"],"_links":{"self":[{"href":"https:\/\/elviox.gr\/en\/wp-json\/wp\/v2\/portfolio\/641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elviox.gr\/en\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/elviox.gr\/en\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/elviox.gr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elviox.gr\/en\/wp-json\/wp\/v2\/comments?post=641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elviox.gr\/en\/wp-json\/wp\/v2\/media\/335"}],"wp:attachment":[{"href":"https:\/\/elviox.gr\/en\/wp-json\/wp\/v2\/media?parent=641"}],"wp:term":[{"taxonomy":"portfolio-types","embeddable":true,"href":"https:\/\/elviox.gr\/en\/wp-json\/wp\/v2\/portfolio-types?post=641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}